{"id":715,"date":"2019-03-16T16:26:19","date_gmt":"2019-03-16T15:26:19","guid":{"rendered":"http:\/\/www.cleanlaser.de\/?page_id=715"},"modified":"2024-07-22T14:00:58","modified_gmt":"2024-07-22T12:00:58","slug":"restaurieren","status":"publish","type":"page","link":"https:\/\/www.cleanlaser.de\/de\/anwendungen\/anwendungsfelder\/restaurieren\/","title":{"rendered":"Restaurieren"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row el_class=&#8221;bg-gray subpage-section&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221; el_class=&#8221;container&#8221;][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h2>Restaurieren und Konservieren mit Laserlicht<\/h2>\n<p>Die cleanLASER-Reinigungstechnologie ist ein schonendes und effizientes Werkzeug zum Restaurieren und Fassadenreinigen. Stein- und Metalloberfl\u00e4chen lassen sich mit dem cleanLASER auch von hartn\u00e4ckigem Umweltschmutz und Verwitterungen befreien.<\/p>\n<ul class=\"list\">\n<li>\n<div class=\"arrow-list\">\n<ul>\n<li>Schonende Reinigung durch Laserlicht<\/li>\n<li>Keine Abrasion durch Strahlmittel<\/li>\n<li>Keinerlei mechanische oder chemische Einwirkung<\/li>\n<li>Keine Sch\u00e4den durch Feuchtigkeit<\/li>\n<li>Leichte Handhabung<\/li>\n<li>Mobiles Werkzeug f\u00fcr umweltfreundliches und zugleich wirtschaftliches Arbeiten<\/li>\n<\/ul>\n<\/div>\n<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;1470&#8243; img_size=&#8221;300&#215;400&#8243;][vc_column_text]Kennen Sie schon die <a href=\"https:\/\/www.cleanlaser.de\/de\/news\/terra-x-zdf\/\">Dokumentation von Terra X<\/a>, in der es u.a. um die schonende Laserreinigung in der Restaurierung geht?[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;bg-white subpage-section&#8221;][vc_column][vc_row_inner el_class=&#8221;container&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;1472&#8243; img_size=&#8221;300&#215;420&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h2>Einige ausgew\u00e4hlte Anwendungen<\/h2>\n<ul class=\"dots\">\n<li>\n<div class=\"circle-list\">\n<ul>\n<li><a href=\"https:\/\/www.cleanlaser.de\/de\/anwendungen\/anwendungsfelder\/restaurieren\/bauwerke-und-fassaden-restaurieren\/\">Steinfassaden und Bauwerke<\/a>\n<ul>\n<li>Schloss Babelsberg<\/li>\n<li><a href=\"https:\/\/www.cleanlaser.de\/de\/news\/cleanlaser-reinigt-das-jefferson-memorial-in-washington-d-c\/\">Jefferson Memorial <\/a>in Washington D.C.<\/li>\n<li><a href=\"https:\/\/www.cleanlaser.de\/de\/news\/driehaus-museum\/\">Museum in Chicago<\/a><\/li>\n<li><a href=\"https:\/\/biancamadden.com\/projects\/conservation-laser-cleaning-in-cairos-city-of-the-dead\/\" target=\"_blank\" rel=\"noopener nofollow\">Mausoleum in Kairos City of Dead<\/a><\/li>\n<li>Rathaus in Ottawa<\/li>\n<li>Rathaus in Philadelphia<\/li>\n<li>Oxford<\/li>\n<li>Hochhaus in Charlotte<\/li>\n<\/ul>\n<\/li>\n<li><a href=\"https:\/\/www.cleanlaser.de\/de\/anwendungen\/anwendungsfelder\/restaurieren\/figuren-restaurieren\/\">Figuren und Ornamente<\/a>\n<ul>\n<li>K\u00f6lner Dom<\/li>\n<li>Ulmer M\u00fcnster<\/li>\n<li>Halberst\u00e4dter Dom<\/li>\n<li>Aachener Rathaus<\/li>\n<li><a href=\"https:\/\/backpacklaser.de\/laser-in-der-restaurierung\" target=\"_blank\" rel=\"noopener nofollow\">Aachener Dom<\/a><\/li>\n<li>Washington<\/li>\n<li>Virginia<\/li>\n<\/ul>\n<\/li>\n<li><a href=\"https:\/\/www.cleanlaser.de\/de\/anwendungen\/anwendungsfelder\/restaurieren\/wandmalereien\/\">Wandmalereien<\/a>\n<ul>\n<li><a href=\"https:\/\/www.cleanlaser.de\/de\/anwendungen\/anwendungsfelder\/restaurieren\/wandmalereien\/\" target=\"_blank\" rel=\"noopener\">\u00c4gypten K\u00f6nigsgr\u00e4ber (Das Grab des <strong>Neferhotep<\/strong>)<\/a><\/li>\n<li>Kirchen (<a href=\"https:\/\/youtu.be\/B4ifT5-pXDo\" target=\"_blank\" rel=\"noopener nofollow\">Video<\/a> anschauen)<\/li>\n<\/ul>\n<\/li>\n<li><a href=\"https:\/\/www.cleanlaser.de\/de\/anwendungen\/anwendungsfelder\/restaurieren\/felsmalereien\/\">Felsmalereien<\/a>\n<ul>\n<li>Australien<\/li>\n<\/ul>\n<\/li>\n<li>Metalle\n<ul>\n<li>Bronze<\/li>\n<li>Silber<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;1475&#8243; img_size=&#8221;medium&#8221;][vc_single_image image=&#8221;1479&#8243; img_size=&#8221;medium&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=&#8221;bg-gray subpage-section&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221; el_class=&#8221;container&#8221;][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text] Restaurieren und Konservieren mit Laserlicht Die cleanLASER-Reinigungstechnologie ist ein schonendes und effizientes Werkzeug zum Restaurieren und Fassadenreinigen. Stein- und Metalloberfl\u00e4chen lassen sich mit dem cleanLASER auch von hartn\u00e4ckigem Umweltschmutz und Verwitterungen befreien. Schonende Reinigung durch Laserlicht Keine Abrasion durch Strahlmittel Keinerlei mechanische oder chemische Einwirkung Keine Sch\u00e4den durch Feuchtigkeit [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1496,"parent":635,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-715","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages\/715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/comments?post=715"}],"version-history":[{"count":22,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages\/715\/revisions"}],"predecessor-version":[{"id":7843,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages\/715\/revisions\/7843"}],"up":[{"embeddable":true,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages\/635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/media\/1496"}],"wp:attachment":[{"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/media?parent=715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}