{"id":2071,"date":"2019-03-18T03:15:22","date_gmt":"2019-03-18T02:15:22","guid":{"rendered":"http:\/\/www.cleanlaser.de\/anwendungen\/anwendungsfelder\/pre-treatment\/joining-pre-treatment-in-gear-production\/"},"modified":"2022-05-20T19:37:40","modified_gmt":"2022-05-20T17:37:40","slug":"fuegevorbehandeln-im-getriebebau","status":"publish","type":"page","link":"https:\/\/www.cleanlaser.de\/de\/anwendungen\/anwendungsfelder\/vorbehandeln\/fuegevorbehandeln-im-getriebebau\/","title":{"rendered":"F\u00fcgevorbehandeln im Getriebebau"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row el_class=&#8221;bg-gray subpage-section&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221; el_class=&#8221;container&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h2>Getriebebau und Antriebsstrang<\/h2>\n<h3>Kompaktanlage &#8220;cleanBOX&#8221; zur Laserreinigung von rotationssymmetrischen Werkst\u00fccken<\/h3>\n<p>Das kompakte Laserbearbeitungssystem cleanBOX reinigt Zylinder, Zahnr\u00e4der und andere Drehteile mit einem Durchmesser von bis zu 200 mm. Die rotationssymmetrischen Werkst\u00fccke \u2013 wie sie meist im Getriebe- und Antriebsstrang zu finden sind \u2013 lassen sich r\u00fcckstandsfrei reinigen, ohne dabei die Passungen bzw. Presspassungen zu ver\u00e4ndern.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;2069&#8243; img_size=&#8221;300&#215;250&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;2067&#8243; img_size=&#8221;300&#215;250&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;bg-white subpage-section&#8221;][vc_column][vc_row_inner el_class=&#8221;container&#8221;][vc_column_inner][vc_column_text]<\/p>\n<h2>Ausstattung<\/h2>\n<ul class=\"list\">\n<li>\n<div class=\"arrow-list\">\n<ul>\n<li>Solides Maschinen-Grundgestell in Kompaktbauweise<\/li>\n<li>Pr\u00e4zisions-Rundschalttisch mit leistungsstarkem Servoantrieb<\/li>\n<li>Bauteilspezifische Werkst\u00fccktr\u00e4ger<\/li>\n<li>Modulare Bauweise<\/li>\n<li>Hydraulisch unterst\u00fctzte Schutzhaube<\/li>\n<li>Integrierte Absaugd\u00fcsen und Rohrleitungen<\/li>\n<li>Schaltschrank mit kompletter Steuerungstechnik<\/li>\n<li>SPS-Steuerung mit Visualisierung<\/li>\n<li>Komplettsystem mit integriertem Lasersystem<\/li>\n<li>Lasersichere Ausf\u00fchrung<\/li>\n<\/ul>\n<\/div>\n<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;bg-gray subpage-section&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221; el_class=&#8221;container&#8221;][vc_column_inner][vc_column_text]Neben der Stand-Alone-Variante entwickelte cleanLASER ein System zur Integration in die bestehende Linienproduktion. Durch die modulare Bauweise ist die cleanBOX leicht zug\u00e4nglich und sp\u00e4ter erweiterbar. Die Anlage kann parallel zur Hauptbearbeitungszeit manuell oder automatisiert best\u00fcckt werden. Durch die kurze Schaltzeit des Rundschalttisches l\u00e4sst sich das Lasersystem nahezu ununterbrochen f\u00fcr die Reinigung nutzen, da die Nebenzeiten minimiert werden. F\u00fcr verschiedene Bauteiltypen reicht ein kurzer R\u00fcstvorgang.<\/p>\n<p>Mit den sehr kompakten, gepulsten Festk\u00f6rperlasern der Low Power Serie (z.B. CL 50\/CL100) l\u00e4sst sich eine hohe Prozesseffizienz bei verschiedenen Aufgaben erzielen. Die verdampften Fette, \u00d6le und Verschmutzungen werden unmittelbar abgesaugt. Ein CLL Control Daten Logger System erm\u00f6glicht auch im Nachfeld das Auslesen der Laserbetriebsdaten.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;bg-white subpage-section&#8221;][vc_column][vc_row_inner el_class=&#8221;container&#8221;][vc_column_inner][vc_column_text]<\/p>\n<h2>Vorteile<\/h2>\n<ul class=\"list\">\n<li>\n<div class=\"arrow-list\">\n<ul>\n<li>Trockene Reinigung ohne Chemie<\/li>\n<li>Sehr geringe Energieaufnahme von typ. &lt;1 kWh<\/li>\n<li>Direkte In-Line-Verkettung<\/li>\n<li>Kompakter Footprint (ca. 2 m\u00b2)<\/li>\n<li>Nachweislich r\u00fcckstandsfreie Reinigung ohne Bauteilsch\u00e4digung<\/li>\n<li>Lokal begrenzte Reinigung (erspart ggf. Korrosionsschutz)<\/li>\n<li>Kurze Taktzeit<\/li>\n<\/ul>\n<\/div>\n<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;bg-gray subpage-section&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221; el_class=&#8221;container&#8221;][vc_column_inner][vc_column_text]<\/p>\n<ul class=\"cl clearfix\">\n<li>\n<div class=\"circle-list\">\n<ul>\n<li>Auch phosphatierte Oberfl\u00e4chen lassen sich im Schwei\u00dfnahtbereich entschichten, so dass Restphosphate r\u00fcckstandsfrei entfernt werden<\/li>\n<li>Durch die Reinigung mit diodengepumpten Lasersystemen ist eine bislang unerreichte Reinigungsqualit\u00e4t und damit eine optimale Nahtqualit\u00e4t erzielbar<\/li>\n<li>Optionale Prozess\u00fcberwachungstechnik erm\u00f6glicht eine 100%ige In-line-Kontrolle des Reinigungsprozesses f\u00fcr eine gleichbleibend perfekte Nahtqualit\u00e4t<\/li>\n<li>Konzipiert f\u00fcr den 24\/7 Non-Stop-Einsatz zum \u00fcberraschend g\u00fcnstigen Komplettpreis<\/li>\n<li>Optional mit integrierter Bauteilkennzeichnung erh\u00e4ltlich<\/li>\n<\/ul>\n<\/div>\n<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=&#8221;bg-gray subpage-section&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221; el_class=&#8221;container&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text] Getriebebau und Antriebsstrang Kompaktanlage &#8220;cleanBOX&#8221; zur Laserreinigung von rotationssymmetrischen Werkst\u00fccken Das kompakte Laserbearbeitungssystem cleanBOX reinigt Zylinder, Zahnr\u00e4der und andere Drehteile mit einem Durchmesser von bis zu 200 mm. Die rotationssymmetrischen Werkst\u00fccke \u2013 wie sie meist im Getriebe- und Antriebsstrang zu finden sind \u2013 lassen sich r\u00fcckstandsfrei reinigen, ohne dabei [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":710,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2071","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages\/2071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/comments?post=2071"}],"version-history":[{"count":5,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages\/2071\/revisions"}],"predecessor-version":[{"id":2076,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages\/2071\/revisions\/2076"}],"up":[{"embeddable":true,"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/pages\/710"}],"wp:attachment":[{"href":"https:\/\/www.cleanlaser.de\/de\/wp-json\/wp\/v2\/media?parent=2071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}